{"id":2002,"date":"2017-03-17T11:09:54","date_gmt":"2017-03-17T10:09:54","guid":{"rendered":"http:\/\/manuelitaitaly.com\/it\/?page_id=2002"},"modified":"2017-03-20T12:02:10","modified_gmt":"2017-03-20T11:02:10","slug":"cosa-facciamo","status":"publish","type":"page","link":"https:\/\/manuelitaitaly.com\/it\/cosa-facciamo\/","title":{"rendered":"Cosa Facciamo"},"content":{"rendered":"<p>La Manuelita si propone come partner ideale per realizzare <strong>calzature di alta qualit\u00e0 rigorosamente Made in Italy<\/strong>. In particolare, \u00e8 in grado di offrire:<\/p>\n<ul>\n<li>Produzioni di\u00a0<strong>collezioni complete<\/strong><\/li>\n<li>Produzioni per il\u00a0<strong>riassortimento degli ordini<\/strong><\/li>\n<li>Creazioni di\u00a0<strong>Capsule Collection<\/strong><\/li>\n<li><strong>Campionari<\/strong> e calzature\u00a0<strong>Made to Order\u00a0<\/strong>e\u00a0<strong>Made to Measure<\/strong><\/li>\n<li>Lavorazione di\u00a0<strong>piccole quantit\u00e0<\/strong>, con l\u2019<strong>attenzione completa al singolo paio<\/strong><\/li>\n<\/ul>\n<p>I\u00a0<strong>servizi<\/strong>\u00a0de La Manuelita, inoltre, sono\u00a0<strong>configurabili e modulabili<\/strong>\u00a0in base alle esigenze di ciascun cliente che potr\u00e0 decidere di <strong>farsi supportare dalla progettazione alla produzione della calzatura oppure solo su una singola attivit\u00e0 o su una singola parte del processo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Manuelita si propone come partner ideale per realizzare calzature di alta qualit\u00e0 rigorosamente Made in Italy. In particolare, \u00e8 in grado di offrire: Produzioni di\u00a0collezioni complete Produzioni per il\u00a0riassortimento degli ordini Creazioni di\u00a0Capsule Collection Campionari e calzature\u00a0Made to Order\u00a0e\u00a0Made to Measure Lavorazione di\u00a0piccole quantit\u00e0, con l\u2019attenzione completa al singolo paio I\u00a0servizi\u00a0de La Manuelita, inoltre, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":563,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full.php","meta":[],"_links":{"self":[{"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/pages\/2002"}],"collection":[{"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/comments?post=2002"}],"version-history":[{"count":4,"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/pages\/2002\/revisions"}],"predecessor-version":[{"id":2060,"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/pages\/2002\/revisions\/2060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/media\/563"}],"wp:attachment":[{"href":"https:\/\/manuelitaitaly.com\/it\/wp-json\/wp\/v2\/media?parent=2002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}