{"id":46,"date":"2017-03-20T17:19:42","date_gmt":"2017-03-20T16:19:42","guid":{"rendered":"http:\/\/manuelitaitaly.com\/en\/?page_id=46"},"modified":"2017-03-20T17:29:43","modified_gmt":"2017-03-20T16:29:43","slug":"contacts","status":"publish","type":"page","link":"https:\/\/manuelitaitaly.com\/en\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"<div id=\"pl-46\"  class=\"panel-layout\" ><div id=\"pg-46-0\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-46-0\" ><div id=\"pgc-46-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-46-0-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"textwidget\"><h3 style=\"text-align: center;\"><strong>La Manuelita Srl<\/strong><\/h3>\n<p style=\"text-align: center;\">Via Enrico Berlinguer, 15<br \/>\n63844 Grottazzolina (FM)<\/p>\n<p style=\"text-align: center;\">Tel. 0734 633376<br \/>\nFax 0734 631916<br \/>\ninfo@manuelitaitaly.com<\/p>\n<p style=\"text-align: center;\">P.IVA 01597530433<\/p>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-46-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-46-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-46-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"textwidget\"><p><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f50-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/46#wpcf7-f50-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"50\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f50-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Your Name (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your Email (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Subject<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your Message<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/p>\n<\/div><\/div><\/div><div id=\"pgc-46-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-46-1-1-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"textwidget\"><div class=\"iframe-resp-container iframe-resp-container-4x3\">\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2911.854799176445!2d13.620671115053979!3d43.1285763791427!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x133208a77623fe7d%3A0x6a13932262366921!2sCalzaturificio+La+Manuelita!5e0!3m2!1sit!2sch!4v1490025787528\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La Manuelita Srl Via Enrico Berlinguer, 15 63844 Grottazzolina (FM) Tel. 0734 633376 Fax 0734 631916 info@manuelitaitaly.com P.IVA 01597530433<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full.php","meta":[],"_links":{"self":[{"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/pages\/46"}],"collection":[{"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":5,"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/pages\/46\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/manuelitaitaly.com\/en\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}